{"id":6439,"date":"2023-10-19T06:30:12","date_gmt":"2023-10-19T11:00:12","guid":{"rendered":"https:\/\/esviafm.com\/?p=6439"},"modified":"2023-10-19T06:30:12","modified_gmt":"2023-10-19T11:00:12","slug":"velasquez-no-existen-inhabilitados-aquel-que-salga-electo-en-la-primaria-debe-ser-respaldado","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/velasquez-no-existen-inhabilitados-aquel-que-salga-electo-en-la-primaria-debe-ser-respaldado\/","title":{"rendered":"Vel\u00e1squez: No existen inhabilitados, aquel que salga electo en la primaria debe ser respaldado"},"content":{"rendered":"<p>Andr\u00e9s Vel\u00e1squez, abanderado de La Causa R, reafirm\u00f3 que todas las organizaciones pol\u00edticas que han participado en el proceso se comprometieron a apoyar y respaldar al candidato que resulte triunfador en la primaria.<\/p>\n<p>En una entrevista concedida a El Nacional, dijo que ese compromiso debe respetarse independientemente de si el ganador est\u00e1 habilitado o inhabilitado.<\/p>\n<p>\u201cPara m\u00ed no existen inhabilitados. De manera que aquel que salga electo en la primaria debe ser respaldado y apoyado por el resto de los candidatos participantes. Eso fue acordado y firmado en acto p\u00fablico\u201d, expres\u00f3 Vel\u00e1squez.<\/p>\n<p>El dirigente pol\u00edtico ahond\u00f3 en su propuesta de gobierno, la cual se fundamenta en un plan de reconstrucci\u00f3n nacional denominado \u201cLa Venezuela digna y sustentable\u201d. Al respecto asegur\u00f3 que se trata de un programa viable bajo par\u00e1metros de dignidad y valores apoyado en tres ejes fundamentales, a saber, dignificar la econom\u00eda, dignificar a las personas y dignificar la pol\u00edtica.<\/p>\n<p>El candidato brind\u00f3 un panorama de la situaci\u00f3n institucional, pol\u00edtica y social del pa\u00eds y en ese sentido indic\u00f3: \u201cVenezuela est\u00e1 sumergida en una profunda crisis producto de la m\u00e1s grande estafa pol\u00edtica que conozcamos. Tenemos un pa\u00eds pr\u00e1cticamente en extinci\u00f3n donde todo ha sido barrido y nada queda en pie. Sin soberan\u00eda, sin instituciones, sin aparato productivo, infraestructura destruida, sin empleos, sin salarios, sin servicios p\u00fablicos, corrupci\u00f3n hasta m\u00e1s no poder y sin libertad ni democracia. Esa es la Venezuela que nos toca reconstruir\u201d.<\/p>\n<p>Explic\u00f3 que su plan de gobierno se enfocar\u00e1 en el aspecto econ\u00f3mico para darle una base s\u00f3lida a la reforma social para luchar contra la pobreza.<\/p>\n<p>\u201cPara ello daremos paso a una amplia apertura petrolera, que vengan todos los capitales privados a invertir en nuestra Pdvsa. Crearemos el Fondo Nacional de Regal\u00edas Petroleras, para atender la Seguridad Social y para establecer el Fondo de Pensiones, que nos permita entregarle una pensi\u00f3n digna a todos los pensionados del pa\u00eds tal como lo establece nuestra Constituci\u00f3n\u201d, se\u00f1al\u00f3.<\/p>\n<p>Por \u00faltimo, Vel\u00e1squez a\u00f1adi\u00f3 que otro de los aspectos prioritarios de su plan es establecer la seguridad jur\u00eddica necesaria para las inversiones y garantizar la propiedad. Es decir, reglas claras para la econom\u00eda.<\/p>\n<p><strong>Fuente : El Impulso\u00a0<\/strong><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_6439\" class=\"pvc_stats all  \" data-element-id=\"6439\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Andr\u00e9s Vel\u00e1squez, abanderado de La Causa R, reafirm\u00f3 que todas las organizaciones pol\u00edticas que han participado en el proceso se comprometieron a apoyar y respaldar al candidato que resulte triunfador en la primaria. En una entrevista concedida a El Nacional, dijo que ese compromiso debe respetarse independientemente de si el ganador est\u00e1 habilitado o inhabilitado. [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_6439\" class=\"pvc_stats all  \" data-element-id=\"6439\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-6439","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"a3_pvc":{"activated":true,"total_views":25,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/6439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=6439"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/6439\/revisions"}],"predecessor-version":[{"id":6441,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/6439\/revisions\/6441"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=6439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=6439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=6439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}