{"id":6243,"date":"2023-10-17T06:39:57","date_gmt":"2023-10-17T11:09:57","guid":{"rendered":"https:\/\/esviafm.com\/?p=6243"},"modified":"2023-10-17T06:39:57","modified_gmt":"2023-10-17T11:09:57","slug":"iris-varela-asegura-que-durante-su-gestion-en-el-ministerio-de-asuntos-penitenciarios-dejo-paz-en-las-carceles","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/iris-varela-asegura-que-durante-su-gestion-en-el-ministerio-de-asuntos-penitenciarios-dejo-paz-en-las-carceles\/","title":{"rendered":"Iris Varela asegura que durante su gesti\u00f3n en el ministerio de Asuntos Penitenciarios dej\u00f3 paz en las c\u00e1rceles"},"content":{"rendered":"<p>La\u00a0<strong>diputada a la Asamblea Nacional chavista, Iris Varela<\/strong>, asegur\u00f3 en un\u00a0programa de televisi\u00f3n\u00a0que durante su gesti\u00f3n como\u00a0<strong>ministra de Asuntos Penitenciarios<\/strong>\u00a0la pacificaci\u00f3n de las c\u00e1rceles lleg\u00f3 casi a un 100%.<\/p>\n<p>\u201cNo hay otro pa\u00eds del mundo donde haya un ministerio que atienda a la poblaci\u00f3n penitenciaria como lo hay aqu\u00ed en Venezuela. Tomar una c\u00e1rcel no es sencillo porque son seres humanos los que est\u00e1n ah\u00ed. Yo dej\u00e9 en 95% la pacificaci\u00f3n de las c\u00e1rceles\u201d, sostuvo Varela en una entrevista televisiva.<\/p>\n<p>Varela\u00a0<strong>neg\u00f3 que el Tren de Aragua tenga ramificaciones en Latinoam\u00e9rica<\/strong>\u00a0y no se refiri\u00f3 a un eventual paradero de\u00a0<strong>H\u00e9ctor Rusthenford Guerrero Flores, alias \u00abNi\u00f1o Guerrero\u00bb<\/strong>, ex pran de la\u00a0<strong>c\u00e1rcel de Tocor\u00f3n<\/strong>\u00a0en el estado Aragua.<\/p>\n<p>\u201cEst\u00e1n tratando de hacer creer que Venezuela est\u00e1 exportando delincuencia, hablan del Tren del Llano, del Tren de Aragua. No es as\u00ed. Cada pa\u00eds latinoamericano tiene bandas de delincuencia organizada\u201d, dijo la exministra.<\/p>\n<p>Pa\u00edses como\u00a0<strong>Colombia, Ecuador y Per\u00fa<\/strong>\u00a0se mantienen en alerta m\u00e1xima ante la posible llegada del pran venezolano.<\/p>\n<p>uerrero, quien estaba en Tocor\u00f3n,\u00a0<strong>se escap\u00f3 del penal junto a sus lugartenientes<\/strong>\u00a0antes de que llegaran los funcionarios que participaron en el operativo.<\/p>\n<p>Frente a esta situaci\u00f3n, Interpol emiti\u00f3 una alerta roja de seguridad en<strong>\u00a0194 pa\u00edses para la b\u00fasqueda del delincuente<\/strong>.<\/p>\n<p>De acuerdo con el Observatorio Venezolano de Prisiones,\u00a0<strong>pa\u00edses de Latinoam\u00e9rica intensificaron la seguridad en las fronteras<\/strong>\u00a0y est\u00e1n coordinando esfuerzos para capturar al l\u00edder y a otros miembros de la organizaci\u00f3n criminal.<\/p>\n<p>La parlamentaria calific\u00f3 como un \u00e9xito la\u00a0<strong>Operaci\u00f3n de Liberaci\u00f3n Cacique Guaicaipuro<\/strong>\u00a0el pasado mi\u00e9rcoles 20 de septiembre, en la cual m\u00e1s de 10 mil funcionarios de seguridad\u00a0 incursionaron en Tocor\u00f3n.<\/p>\n<p>Aunque\u00a0<strong>el Estado todav\u00eda no ha ofrecido cifras oficiales de muertos y heridos<\/strong>, Varela indic\u00f3 que muchos apostaban por un derramamiento masivo de sangre.<\/p>\n<p>\u201cPues no tuvieron la masacre, fue impecable en cuanto al respeto a la poblaci\u00f3n penitenciaria la forma c\u00f3mo se organiz\u00f3 la toma. Hay que felicitar al gobierno revolucionario por haber derribado uno de los mitos que hab\u00eda con ese centro penitenciario en particular\u201d, destac\u00f3 Varela.<\/p>\n<p><strong>Fuente : Run Run\u00a0<\/strong><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_6243\" class=\"pvc_stats all  \" data-element-id=\"6243\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0diputada a la Asamblea Nacional chavista, Iris Varela, asegur\u00f3 en un\u00a0programa de televisi\u00f3n\u00a0que durante su gesti\u00f3n como\u00a0ministra de Asuntos Penitenciarios\u00a0la pacificaci\u00f3n de las c\u00e1rceles lleg\u00f3 casi a un 100%. \u201cNo hay otro pa\u00eds del mundo donde haya un ministerio que atienda a la poblaci\u00f3n penitenciaria como lo hay aqu\u00ed en Venezuela. Tomar una c\u00e1rcel no [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_6243\" class=\"pvc_stats all  \" data-element-id=\"6243\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-6243","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"a3_pvc":{"activated":true,"total_views":26,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/6243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=6243"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/6243\/revisions"}],"predecessor-version":[{"id":6245,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/6243\/revisions\/6245"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=6243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=6243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=6243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}