{"id":5806,"date":"2023-10-09T06:12:57","date_gmt":"2023-10-09T10:42:57","guid":{"rendered":"https:\/\/esviafm.com\/?p=5806"},"modified":"2023-10-09T06:12:57","modified_gmt":"2023-10-09T10:42:57","slug":"capriles-renuncia-a-las-primarias-dejo-en-manos-de-las-bases-de-pj-una-construccion-viable-para-2024","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/capriles-renuncia-a-las-primarias-dejo-en-manos-de-las-bases-de-pj-una-construccion-viable-para-2024\/","title":{"rendered":"Capriles renuncia a las primarias: Dejo en manos de las bases de PJ una construcci\u00f3n viable para 2024"},"content":{"rendered":"<div><span>El dos veces candidato presidencial de la Mesa de la Unidad Democr\u00e1tica opositora, Henrique Capriles Radonski, anunci\u00f3 su decisi\u00f3n de retirarse de las primarias de la Plataforma Unitaria que est\u00e1n previstas para el pr\u00f3ximo 22 de octubre.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>Este domingo, a trav\u00e9s de sus redes sociales el postulado por el partido Primero Justicia (PJ), anunci\u00f3 que no participar\u00e1 en la consulta interna opositora, que se realizar\u00e1 dentro de dos domingos.<\/span><\/div>\n<div><\/div>\n<div>\n<div><span>Asegur\u00f3 que tom\u00f3 la decisi\u00f3n como militante y no como l\u00edder pol\u00edtico para lograr el cambio en Venezuela.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>\u201cYo creo que es claro lo que tengo que hacer, que es facilitar, ayudar a construir la ruta del a\u00f1o 2024. Es ponerme del lado de la unidad, que es volver a donde siempre hemos estado y no lo hemos hecho desde una jerarqu\u00eda, cargo o posici\u00f3n de nombramiento\u2026 sino como militante\u201d, expres\u00f3.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>Asimismo indic\u00f3\u00a0<\/span><span>que \u00abten\u00eda que facilitar una opci\u00f3n que pueda materializar el objetivo, que en su caso no pod\u00eda ser al tener seis a\u00f1os inhabilitado por la Contralor\u00eda General de la Rep\u00fablica. Y adem\u00e1s, pese a una decisi\u00f3n a su favor de la Comisi\u00f3n Interamericana\u00a0<\/span><span>de Derechos Humanos (CIDH), el Tribunal Supremo de Justicia a\u00fan no le responde\u00bb.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>\u201cEs obvio que tenemos que ayudar, que tenemos que facilitar la construcci\u00f3n de la unidad, que no podemos seguir dejando que pase el tiempo como si a \u00faltimo minuto vamos a construir la unidad superior que necesitamos.\u00a0Por eso creo que lo mejor, ya a m\u00ed me eligieron las bases de Primero Justicia\u2026 desde la gratitud, desde el respeto pongo en sus manos la construcci\u00f3n de una opci\u00f3n viable para el 2024\u201d, puntualiz\u00f3.<\/span><\/div>\n<div><span>\u00a0<\/span><\/div>\n<div><span>Tambi\u00e9n detall\u00f3 que en las pr\u00f3ximas horas va a consignar una carta a la Comisi\u00f3n de Primarias \u201cy a echar pa&#8217; lante compa\u00f1eras y compa\u00f1eros.\u00a0Salir el 22 (de octubre) con la mirada puesta en 2024. Lo dem\u00e1s es desgastarnos entre nosotros, es pelearnos por lo peque\u00f1o.\u00a0Aqu\u00ed lo que est\u00e1 en juego es Venezuela, el futuro de cada uno de ustedes\u201d.<\/span><\/div>\n<\/div>\n<div><\/div>\n<div><strong>Fuente : Globovision\u00a0<\/strong><\/div>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5806\" class=\"pvc_stats all  \" data-element-id=\"5806\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El dos veces candidato presidencial de la Mesa de la Unidad Democr\u00e1tica opositora, Henrique Capriles Radonski, anunci\u00f3 su decisi\u00f3n de retirarse de las primarias de la Plataforma Unitaria que est\u00e1n previstas para el pr\u00f3ximo 22 de octubre. \u00a0 Este domingo, a trav\u00e9s de sus redes sociales el postulado por el partido Primero Justicia (PJ), anunci\u00f3 [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5806\" class=\"pvc_stats all  \" data-element-id=\"5806\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5806","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"a3_pvc":{"activated":true,"total_views":23,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/5806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=5806"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/5806\/revisions"}],"predecessor-version":[{"id":5808,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/5806\/revisions\/5808"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=5806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=5806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=5806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}