{"id":41858,"date":"2026-09-01T06:39:34","date_gmt":"2026-09-01T11:09:34","guid":{"rendered":"https:\/\/esviafm.com\/?p=41858"},"modified":"2026-09-01T06:39:34","modified_gmt":"2026-09-01T11:09:34","slug":"trump-sobre-la-permanencia-de-venezuela-en-la-opep-eso-depende-de-ellos","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/trump-sobre-la-permanencia-de-venezuela-en-la-opep-eso-depende-de-ellos\/","title":{"rendered":"Trump sobre la permanencia de Venezuela en la OPEP: \u00abEso depende de ellos\u00bb"},"content":{"rendered":"<p>El presidente de Estados Unidos Donald Trump evit\u00f3 pronunciarse sobre una eventual salida de Venezuela de la Organizaci\u00f3n de Pa\u00edses Exportadores de Petr\u00f3leo (OPEP) y afirm\u00f3 que esa decisi\u00f3n corresponder\u00e1 exclusivamente al gobierno interino de Delcy Rodr\u00edguez.<\/p>\n<p>La declaraci\u00f3n se produjo despu\u00e9s de que Washington y Caracas anunciaron un acuerdo energ\u00e9tico que permitir\u00e1 a empresas estadounidenses participar en el desarrollo de una parte significativa de las reservas petroleras venezolanas. Venezuela es uno de los pa\u00edses fundadores de la OPEP y mantiene su condici\u00f3n de miembro desde la creaci\u00f3n de la organizaci\u00f3n en 1960.<\/p>\n<p>\u201cNo lo s\u00e9, eso depende de ellos. Eso va a ser una decisi\u00f3n suya\u201d, respondi\u00f3 Trump al ser consultado por medios sobre si Venezuela deber\u00eda continuar en el organismo petrolero tras el acuerdo que permitir\u00e1 a compa\u00f1\u00edas estadounidenses acceder a cerca de 65 mil millones de barriles de reservas venezolanas.<\/p>\n<p>El mandatario estadounidense defendi\u00f3 al mismo tiempo el nuevo esquema de cooperaci\u00f3n energ\u00e9tica entre ambos pa\u00edses y asegur\u00f3 que Washington y Caracas mantienen una relaci\u00f3n favorable en torno a la explotaci\u00f3n y comercializaci\u00f3n del crudo.<\/p>\n<p>\u201cTenemos una gran relaci\u00f3n con Venezuela. En cierto sentido, formamos un equipo: extraemos millones y millones de barriles de petr\u00f3leo que se env\u00edan a Houston, a Luisiana y a muchos otros lugares de Estados Unidos y de todo el mundo; estamos ganando una fortuna, y ellos tambi\u00e9n\u201d, explic\u00f3 el mandatario con respecto al acuerdo.<\/p>\n<div class=\"wp-block-spacer\" aria-hidden=\"true\"><\/div>\n<p class=\"has-medium-font-size\"><strong>Venezuela prev\u00e9 producir 1,5 millones de barriles diarios<\/strong><\/p>\n<p>La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, ofreci\u00f3 el s\u00e1bado detalles sobre el alcance del convenio. De acuerdo con su explicaci\u00f3n, el proyecto tendr\u00e1 duraci\u00f3n de 25 a\u00f1os y contempla elevar la producci\u00f3n hasta 1,5 millones de barriles diarios.<\/p>\n<p>El plan incluye el desarrollo de 17 campos estrat\u00e9gicos, que seg\u00fan Rodr\u00edguez concentran \u201cun potencial probado de 65 mil millones de barriles de petr\u00f3leo\u201d.<\/p>\n<p>Entre los proyectos previstos se encuentran ocho bloques verdes localizados en la Faja Petrol\u00edfera del Orinoco, una extensa zona petrolera situada en el centro-este y este de Venezuela.<\/p>\n<p>Rodr\u00edguez indic\u00f3 que los proyectos contemplar\u00e1n regal\u00edas m\u00ednimas de 16% e impuestos sobre la renta de 34%. Seg\u00fan la presidenta interina, estos ingresos permitir\u00e1n contribuir al proceso de recuperaci\u00f3n econ\u00f3mica del pa\u00eds.<\/p>\n<div class=\"wp-block-spacer\" aria-hidden=\"true\"><\/div>\n<p class=\"has-medium-font-size\"><strong>Trump espera que el crudo venezolano llegue r\u00e1pidamente a EE UU<\/strong><\/p>\n<p>Para la administraci\u00f3n estadounidense, el convenio tambi\u00e9n representa una v\u00eda para incrementar el suministro de petr\u00f3leo a su mercado interno.<\/p>\n<p>Trump ha sostenido que el aumento de los env\u00edos venezolanos podr\u00eda contribuir a reducir los precios de la gasolina en Estados Unidos. Su gobierno busca incrementar el abastecimiento energ\u00e9tico despu\u00e9s de que el conflicto con Ir\u00e1n y las dificultades en el estrecho de Ormuz afectaran el flujo internacional de crudo y redujeran las reservas estrat\u00e9gicas estadounidenses.<\/p>\n<p>El presidente estadounidense rechaz\u00f3 adem\u00e1s las estimaciones de especialistas que calculan que los nuevos suministros venezolanos tardar\u00e1n a\u00f1os en reflejarse de manera significativa en el mercado estadounidense.<\/p>\n<p>\u201cVa a ir r\u00e1pido, mucho m\u00e1s r\u00e1pido de lo que predicen los analistas, que hablan de dos o tres a\u00f1os. Incluso si fueran dos a\u00f1os, ese es un periodo de tiempo breve\u201d, respondi\u00f3 Trump al ser preguntado por los argumentos de la mayor\u00eda de expertos, que apuntan que el flujo de crudo venezolano tardar\u00e1 en sentirse en suelo estadounidense.<\/p>\n<p>El acuerdo petrolero se suma a los cambios en la relaci\u00f3n entre Estados Unidos y Venezuela registrados desde enero, cuando Washington captur\u00f3 al entonces presidente Nicol\u00e1s Maduro.<\/p>\n<p>Desde entonces, la administraci\u00f3n Trump ha estrechado su relaci\u00f3n con el gobierno encabezado interinamente por Rodr\u00edguez y ambos pa\u00edses han avanzado en la normalizaci\u00f3n de sus v\u00ednculos diplom\u00e1ticos.<\/p>\n<p>En este nuevo escenario, el sector petrolero se ha convertido en uno de los principales puntos de cooperaci\u00f3n entre Caracas y Washington, mientras Venezuela mantiene pendiente la decisi\u00f3n sobre su futuro en la OPEP.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_41858\" class=\"pvc_stats all  \" data-element-id=\"41858\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos Donald Trump evit\u00f3 pronunciarse sobre una eventual salida de Venezuela de la Organizaci\u00f3n de Pa\u00edses Exportadores de Petr\u00f3leo (OPEP) y afirm\u00f3 que esa decisi\u00f3n corresponder\u00e1 exclusivamente al gobierno interino de Delcy Rodr\u00edguez. La declaraci\u00f3n se produjo despu\u00e9s de que Washington y Caracas anunciaron un acuerdo energ\u00e9tico que permitir\u00e1 a empresas [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_41858\" class=\"pvc_stats all  \" data-element-id=\"41858\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":41859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17],"tags":[],"class_list":["post-41858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"a3_pvc":{"activated":true,"total_views":3,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/41858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=41858"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/41858\/revisions"}],"predecessor-version":[{"id":41860,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/41858\/revisions\/41860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media\/41859"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=41858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=41858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=41858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}