{"id":39865,"date":"2026-07-15T07:49:47","date_gmt":"2026-07-15T12:19:47","guid":{"rendered":"https:\/\/esviafm.com\/?p=39865"},"modified":"2026-07-15T07:51:30","modified_gmt":"2026-07-15T12:21:30","slug":"saime-habilita-reprogramacion-de-citas-de-pasaporte-suspendidas-por-los-terremotos","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/saime-habilita-reprogramacion-de-citas-de-pasaporte-suspendidas-por-los-terremotos\/","title":{"rendered":"Saime habilita reprogramaci\u00f3n de citas de pasaporte suspendidas por los terremotos"},"content":{"rendered":"<div class=\"single-post-excerpt post-excerpt-at\">El organismo explic\u00f3 que las personas afectadas deber\u00e1n ingresar al portal oficial del Saime y seguir una serie de pasos para cancelar la cita vencida. Una vez completado el procedimiento, el sistema permitir\u00e1 descargar la nueva planilla de la cita, la cual deber\u00e1 ser impresa. La medida se aplica mientras contin\u00faan las labores de recuperaci\u00f3n tras los terremotos del 24 de junio<\/div>\n<div><\/div>\n<div class=\"post-meta-wrap clearfix\">\n<p>El Servicio Administrativo de Identificaci\u00f3n, Migraci\u00f3n y Extranjer\u00eda (Saime) inform\u00f3 que los usuarios con citas de pasaporte asignadas entre el 25 de junio y el 13 de julio podr\u00e1n reprogramar sus tr\u00e1mites, luego de la suspensi\u00f3n temporal de actividades en sus oficinas debido a la emergencia generada por los terremotos del pasado 24 de junio.<\/p>\n<div class=\"google-anno-skip google-anno-sc\" tabindex=\"0\" role=\"link\" aria-label=\"Geolog\u00eda\" data-google-vignette=\"false\" data-google-interstitial=\"false\">\n<p><strong>El organismo explic\u00f3 que las personas afectadas deber\u00e1n ingresar al portal oficial del Saime y seguir una serie de pasos para cancelar la cita vencida<\/strong>\u00a0y seleccionar una nueva fecha disponible.<\/p>\n<p>Para realizar el proceso, los usuarios deben ingresar al sistema con su usuario y contrase\u00f1a, dirigirse al apartado de Pasaporte, ubicar la cita asignada y seleccionar la opci\u00f3n \u201cCancelar\u201d. Posteriormente, deber\u00e1n entrar en la secci\u00f3n \u201c\u00daltima Orden\u201d, elegir la opci\u00f3n \u201cReagendar\u201d y seleccionar una oficina activa, as\u00ed como el nuevo d\u00eda y horario disponible.<\/p>\n<p><strong>Una vez completado el procedimiento, el sistema permitir\u00e1 descargar la nueva planilla de la cita, la cual deber\u00e1 ser impresa<\/strong>\u00a0y presentada el d\u00eda del tr\u00e1mite como requisito obligatorio.<\/p>\n<p>El Saime indic\u00f3 que quienes presenten inconvenientes durante el proceso podr\u00e1n comunicarse al n\u00famero 0-800-SAIME-00 (0-800-72463-00), disponible de lunes a viernes entre las 8:00 a.m. y 4:00 p.m.<\/p>\n<p><strong>Asimismo, habilit\u00f3 la atenci\u00f3n mediante mensajer\u00eda directa en Instagram<\/strong>, donde los usuarios deber\u00e1n proporcionar sus datos personales y explicar el problema presentado para recibir asistencia.<\/p>\n<div class=\"entry-content clearfix single-post-content\">\n<div class=\"continue-reading-content close\">\n<p><strong>La medida se aplica mientras contin\u00faan las labores de recuperaci\u00f3n tras los terremotos del 24 de junio<\/strong>, que ocasionaron da\u00f1os en infraestructura y afectaciones en distintos estados del pa\u00eds, principalmente en La Guaira, Miranda y Caracas. Seg\u00fan el balance oficial m\u00e1s reciente, la emergencia dej\u00f3 4.561 fallecidos, 16.740 heridos y 17.907 personas sin vivienda.<\/p>\n<div class=\"google-anno-skip google-anno-sc\" tabindex=\"0\" role=\"link\" aria-label=\"Geolog\u00eda\" data-google-vignette=\"false\" data-google-interstitial=\"false\"><strong>Fuente : Versi\u00f3n Final\u00a0<\/strong><\/div>\n<\/div>\n<\/div>\n<div class=\"post-share single-post-share bottom-share clearfix style-5\">\n<div class=\"post-share-btn-group\"><\/div>\n<div class=\"share-handler-wrap bs-pretty-tabs bs-pretty-tabs-initialized\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_39865\" class=\"pvc_stats all  \" data-element-id=\"39865\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El organismo explic\u00f3 que las personas afectadas deber\u00e1n ingresar al portal oficial del Saime y seguir una serie de pasos para cancelar la cita vencida. Una vez completado el procedimiento, el sistema permitir\u00e1 descargar la nueva planilla de la cita, la cual deber\u00e1 ser impresa. La medida se aplica mientras contin\u00faan las labores de recuperaci\u00f3n [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_39865\" class=\"pvc_stats all  \" data-element-id=\"39865\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":39866,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[25],"tags":[],"class_list":["post-39865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"a3_pvc":{"activated":true,"total_views":2,"today_views":2},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/39865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=39865"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/39865\/revisions"}],"predecessor-version":[{"id":39867,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/39865\/revisions\/39867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media\/39866"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=39865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=39865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=39865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}