{"id":36580,"date":"2026-03-26T07:01:41","date_gmt":"2026-03-26T11:31:41","guid":{"rendered":"https:\/\/esviafm.com\/?p=36580"},"modified":"2026-03-26T07:01:41","modified_gmt":"2026-03-26T11:31:41","slug":"brasil-presenta-el-primer-caza-supersonico-fabricado-alli","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/brasil-presenta-el-primer-caza-supersonico-fabricado-alli\/","title":{"rendered":"Brasil presenta el primer caza supers\u00f3nico fabricado all\u00ed"},"content":{"rendered":"<p>El fabricante aeron\u00e1utico brasile\u00f1o Embraer present\u00f3 este mi\u00e9rcoles (25.03.2026) el primer caza F-39E Gripen fabricado en\u00a0<a class=\"internal-link\" href=\"https:\/\/www.dw.com\/es\/brasil\/t-17411698\">Brasil<\/a>, marcando un hito para la soberan\u00eda y la industria de defensa nacional, seg\u00fan la Fuerza A\u00e9rea Brasile\u00f1a. Se trata del primer avi\u00f3n de combate supers\u00f3nico fabricado en el pa\u00eds, lo que la Presidencia del pa\u00eds destac\u00f3 como un hito \u00abin\u00e9dito en Am\u00e9rica Latina\u00bb.<\/p>\n<p>Durante una ceremonia solemne en las instalaciones del fabricante brasile\u00f1o en Sao Paulo, el presidente brasile\u00f1o,\u00a0<a class=\"internal-link\" href=\"https:\/\/www.dw.com\/es\/da-silva-luiz-in%C3%A1cio-lula\/t-37389505\">Luiz In\u00e1cio Lula da Silva<\/a>, fue el encargado de bautizar al aparato roci\u00e1ndole una botella de champ\u00e1n sobre el fuselaje gris. El propio Lula calific\u00f3 el momento en redes sociales como \u00abmuy simb\u00f3lico, demostrando un pa\u00eds que cree en s\u00ed mismo, invierte en tecnolog\u00eda y reafirma su soberan\u00eda\u00bb.<\/p>\n<p>\u00abEste proyecto permite consolidar nuestro poder de disuasi\u00f3n, incrementando nuestra capacidad para garantizar la soberan\u00eda nacional y la seguridad regional\u00bb, declar\u00f3 durante el acto el ministro brasile\u00f1o de Defensa, Jos\u00e9 M\u00facio. Tambi\u00e9n presente en el evento, el vicepresidente brasile\u00f1o, Geraldo Alckmin, destac\u00f3 que \u00abla industria de defensa es un seguro para la soberan\u00eda nacional, adem\u00e1s de estar a la vanguardia del desarrollo industrial\u00bb.<\/p>\n<h2>Saab en lugar de Rafale o Boeing<\/h2>\n<p>En total, Brasil encarg\u00f3 a Saab 36 aviones de combate supers\u00f3nicos,\u00a0<a class=\"internal-link\" href=\"https:\/\/www.dw.com\/es\/brasil-recibe-el-primero-de-los-36-cazas-suecos-que-compr%C3%B3\/a-54997409\">el primero de los cuales recibi\u00f3 en septiembre de 2020<\/a>. De ellos,\u00a015 ser\u00e1n fabricados en las instalaciones de Embraer, en Gavi\u00e3o Peixoto. Brasilia prefiri\u00f3 el avi\u00f3n sueco al Rafale del franc\u00e9s Dassault Aviation y al F\/A-18 Super Hornet del fabricante estadounidense Boeing.<\/p>\n<p>Las condiciones de adjudicaci\u00f3n del contrato en 2014 fueron objeto de una\u00a0<a class=\"internal-link\" href=\"https:\/\/www.dw.com\/es\/brasil-nuevo-cargo-de-corrupci%C3%B3n-contra-lula\/a-36716517\">amplia investigaci\u00f3n en Brasil por sospechas de corrupci\u00f3n<\/a>\u00a0en detrimento del Rafale. Procesado en el marco de este caso tras sus primeros mandatos (2003-2010), Lula fue finalmente absuelto por falta de pruebas en 2021.<\/p>\n<p>Brasil reivindica su condici\u00f3n de pa\u00eds pac\u00edfico, pero la defensa se impone cada vez m\u00e1s como un tema clave a la vista del convulso contexto geopol\u00edtico, especialmente con la guerra en Oriente Medio. El gobierno del pa\u00eds m\u00e1s grande de Am\u00e9rica Latina tambi\u00e9n se ha mostrado preocupado por la intervenci\u00f3n militar estadounidense para sacar del poder al presidente venezolano Nicol\u00e1s Maduro.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_36580\" class=\"pvc_stats all  \" data-element-id=\"36580\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El fabricante aeron\u00e1utico brasile\u00f1o Embraer present\u00f3 este mi\u00e9rcoles (25.03.2026) el primer caza F-39E Gripen fabricado en\u00a0Brasil, marcando un hito para la soberan\u00eda y la industria de defensa nacional, seg\u00fan la Fuerza A\u00e9rea Brasile\u00f1a. Se trata del primer avi\u00f3n de combate supers\u00f3nico fabricado en el pa\u00eds, lo que la Presidencia del pa\u00eds destac\u00f3 como un hito [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_36580\" class=\"pvc_stats all  \" data-element-id=\"36580\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":7,"featured_media":36581,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17],"tags":[],"class_list":["post-36580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"a3_pvc":{"activated":true,"total_views":14,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=36580"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36580\/revisions"}],"predecessor-version":[{"id":36582,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36580\/revisions\/36582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media\/36581"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=36580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=36580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=36580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}