{"id":36520,"date":"2026-03-25T06:29:30","date_gmt":"2026-03-25T10:59:30","guid":{"rendered":"https:\/\/esviafm.com\/?p=36520"},"modified":"2026-03-25T06:29:30","modified_gmt":"2026-03-25T10:59:30","slug":"filipinas-declara-emergencia-energetica-por-crisis-en-oriente-medio","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/filipinas-declara-emergencia-energetica-por-crisis-en-oriente-medio\/","title":{"rendered":"Filipinas declara emergencia energ\u00e9tica por crisis en Oriente Medio"},"content":{"rendered":"<p>El\u00a0<strong>presidente de Filipinas, Ferdinand \u201cBongbong\u201d Marcos Jr., declar\u00f3 este martes 24 de marzo la emergencia energ\u00e9tica nacional\u00a0<\/strong>ante el peligro inminente para el suministro de hidrocarburos por el conflicto en Oriente Medio y el bloqueo del estrecho de Ormuz.<\/p>\n<p>La medida convierte a<strong>\u00a0Filipinas en el primer pa\u00eds en aplicar una respuesta tan dr\u00e1stica<\/strong>,\u00a0<strong>a causa directa de la agresi\u00f3n conjunta de Estados Unidos e Israel contra Ir\u00e1n<\/strong>, iniciada el pasado\u00a0<strong>28 de febrero.<\/strong><\/p>\n<p>Con la\u00a0<strong>Orden Ejecutiva N.\u00ba 110,\u00a0<\/strong>el mandatario activ\u00f3 el\u00a0<strong>Paquete Unificado para los Medios de Vida<\/strong>, la Industria, la Alimentaci\u00f3n y el Transporte (UPLIFT).\u00a0<strong>Esta estrategia integral busca coordinar a todo el gabinete para mitigar la volatilidad de los precios y la escasez de combustible.<\/strong><\/p>\n<p>Las\u00a0<strong>autoridades iran\u00edes,<\/strong>\u00a0por su parte, han advertido que\u00a0<strong>no saldr\u00e1 de la regi\u00f3n \u00abni una sola gota de petr\u00f3leo\u00bb por mar mientras persistan las agresiones imperiales<\/strong>, lo que anticipa una escalada en la crisis de abastecimiento global.<\/p>\n<p><strong>Marcos Jr. alert\u00f3\u00a0<\/strong>sobre la posibilidad real de que\u00a0<strong>los aviones queden en tierra por las restricciones de abastecimiento<\/strong>. El jefe de Estado se\u00f1al\u00f3 que diversas naciones ya comunicaron a las\u00a0<strong>aerol\u00edneas filipinas la imposibilidad de suministrarles combustible,<\/strong>\u00a0oblig\u00e1ndolas a cargar reservas para viajes de ida y vuelta.<\/p>\n<p>Esta situaci\u00f3n pone en\u00a0<strong>riesgo cr\u00edtico los vuelos de larga distancia y podr\u00eda paralizar una parte esencial del transporte a\u00e9reo global.<\/strong>\u00a0Ante la\u00a0<strong>inestabilidad de sus fuentes tradicionales<\/strong>, el Gobierno filipino ha manifestado su inter\u00e9s en explorar nuevos proveedores, evaluando la\u00a0<strong>posibilidad de adquirir crudo ruso a pesar de no ser un suministrador hist\u00f3rico.\u00a0<\/strong><\/p>\n<p>Mientras tanto,\u00a0<strong>Malasia se mantiene como la principal fuente de petr\u00f3leo para el archipi\u00e9lago,\u00a0<\/strong>y Jap\u00f3n y Corea del Sur contin\u00faan siendo los<strong>\u00a0abastecedores de combustibles refinados<\/strong>. La\u00a0<strong>crisis energ\u00e9tica global se agudiz\u00f3 considerablemente tras los bombardeos perpetrados por fuerzas estadounidenses e israel\u00edes<\/strong>\u00a0que resultaron en la\u00a0<strong>muerte del l\u00edder supremo de Ir\u00e1n, el ayatol\u00e1 Al\u00ed Jamene\u00ed,<\/strong>\u00a0y de altos mandos militares de la Rep\u00fablica Isl\u00e1mica.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe id=\"telegram-post-teleSUR_tv-124359\" src=\"https:\/\/t.me\/teleSUR_tv\/124359?embed=1\" width=\"100%\" height=\"\" frameborder=\"0\" scrolling=\"no\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>En represalia por este ataque directo a su soberan\u00eda y la\u00a0<strong>destrucci\u00f3n de su infraestructura energ\u00e9tica,<\/strong>\u00a0<strong>Teher\u00e1n bloque\u00f3 el estrat\u00e9gico estrecho de Ormuz.<\/strong>\u00a0Este punto neur\u00e1lgico, que conecta el golfo P\u00e9rsico con el de Om\u00e1n, es fundamental para el comercio mundial, ya que por \u00e9l transita aproximadamente el<strong>\u00a020 por ciento del petr\u00f3leo consumido globalmente<\/strong>, su cierre ha disparado los\u00a0<strong>costos de transporte y seguros mar\u00edtimos a nivel mundial,\u00a0<\/strong>generando una onda expansiva de inestabilidad econ\u00f3mica y financiera.<\/p>\n<p>La Rep\u00fablica Isl\u00e1mica de Ir\u00e1n ha respondido a la\u00a0<strong>agresi\u00f3n con ataques masivos a instalaciones petroleras vinculadas a Estados Unidos en la regi\u00f3n, evidenciando la escalada del conflicto.<\/strong>\u00a0Mientras Washington e Israel mantienen su pol\u00edtica de hostigamiento, pa\u00edses dependientes de la energ\u00eda como\u00a0<strong>Filipinas comienzan a sufrir el impacto directo de una guerra que amenaza con paralizar sectores vitales de la econom\u00eda global y el transporte internacional.<\/strong><\/p>\n<p>Esta situaci\u00f3n subraya la\u00a0<strong>vulnerabilidad de las naciones del Sur global ante las acciones de las potencias imperiales en regiones estrat\u00e9gicas como Oriente Medio,\u00a0<\/strong>y la urgente\u00a0<strong>necesidad de construir una arquitectura energ\u00e9tica\u00a0<\/strong>y de seguridad m\u00e1s justa e independiente.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_36520\" class=\"pvc_stats all  \" data-element-id=\"36520\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0presidente de Filipinas, Ferdinand \u201cBongbong\u201d Marcos Jr., declar\u00f3 este martes 24 de marzo la emergencia energ\u00e9tica nacional\u00a0ante el peligro inminente para el suministro de hidrocarburos por el conflicto en Oriente Medio y el bloqueo del estrecho de Ormuz. La medida convierte a\u00a0Filipinas en el primer pa\u00eds en aplicar una respuesta tan dr\u00e1stica,\u00a0a causa directa de [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_36520\" class=\"pvc_stats all  \" data-element-id=\"36520\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":7,"featured_media":36521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17],"tags":[],"class_list":["post-36520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"a3_pvc":{"activated":true,"total_views":9,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=36520"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36520\/revisions"}],"predecessor-version":[{"id":36522,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36520\/revisions\/36522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media\/36521"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=36520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=36520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=36520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}