{"id":36465,"date":"2026-03-24T06:38:39","date_gmt":"2026-03-24T11:08:39","guid":{"rendered":"https:\/\/esviafm.com\/?p=36465"},"modified":"2026-03-24T06:38:39","modified_gmt":"2026-03-24T11:08:39","slug":"chile-anuncia-alza-historica-de-combustibles-por-la-guerra","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/chile-anuncia-alza-historica-de-combustibles-por-la-guerra\/","title":{"rendered":"Chile anuncia alza hist\u00f3rica de combustibles por la guerra"},"content":{"rendered":"<p>El nuevo gobierno de\u00a0<a class=\"internal-link\" href=\"https:\/\/www.dw.com\/es\/chile\/t-17411731\">Chile<\/a>\u00a0anunci\u00f3 el lunes (23.03.2026) un aumento hist\u00f3rico de casi medio d\u00f3lar por litro en los combustibles, tras hacer un severo ajuste en un mecanismo estatal que amortigua la volatilidad de los precios internacionales.<\/p>\n<p>Chile depende casi en su totalidad de las importaciones de petr\u00f3leo, cuyo valor en las \u00faltimas semanas registr\u00f3 un fuerte incremento de 70 d\u00f3lares a 110 por la guerra que enfrenta a Estados Unidos e Israel contra\u00a0<a class=\"internal-link\" href=\"https:\/\/www.dw.com\/es\/ir%C3%A1n\/t-63346395\">Ir\u00e1n<\/a>\u00a0en Oriente Medio.<\/p>\n<p>La administraci\u00f3n del ultraderechista\u00a0<a class=\"internal-link\" href=\"https:\/\/www.dw.com\/es\/jos%C3%A9-antonio-kast\/t-75154542\">Jos\u00e9 Antonio Kast<\/a>, quien promete una reducci\u00f3n del d\u00e9ficit fiscal, asegura que el mecanismo de control le cuesta al Estado unos 140 millones de d\u00f3lares semanales debido al actual contexto internacional.<\/p>\n<p>Los nuevos precios empezar\u00e1n a regir el jueves. La gasolina pasar\u00e1 de costar unos 1,3 d\u00f3lares por litro a 1,7, mientras que el di\u00e9sel se revalorizar\u00e1 de 1 d\u00f3lar a tambi\u00e9n 1,7.<\/p>\n<p>La medida se hace \u00abpara ajustar los precios internos hacia niveles consistentes con los precios internacionales\u00bb, dijo en un comunicado el Ministerio de Hacienda.<\/p>\n<p>\u00abEstamos enfrentando un shock de los m\u00e1s grandes en el mercado del petr\u00f3leo en d\u00e9cadas, en un contexto de estrechez fiscal muy severa. Tenemos que tomar decisiones duras para resguardar las finanzas p\u00fablicas\u00bb, se\u00f1al\u00f3 Jorge Quiroz, ministro de esa cartera, citado por el comunicado.<\/p>\n<h2>Alto costo de la vida<\/h2>\n<p>Para mitigar la subida del costo de vida de los chilenos, el gobierno anunci\u00f3 medidas como el congelamiento de la tarifa del transporte p\u00fablico y un bono de 110 d\u00f3lares mensual para los taxistas por medio a\u00f1o.<\/p>\n<p>La nueva administraci\u00f3n busca reducir el d\u00e9ficit fiscal que report\u00f3 el pa\u00eds en 2025, de 3,6% del PIB, que el gobierno de su antecesor\u00a0izquierdista Gabriel Boric (2022-2026) atribuy\u00f3 a ingresos menores a los previstos.<\/p>\n<p>Kast, que asumi\u00f3 el poder hace dos semanas, orden\u00f3 la disminuci\u00f3n de un 3% en los gastos de los ministerios para ahorrar unos 3.000 millones de d\u00f3lares en 2026.<\/p>\n<p>El mandatario busca una reducci\u00f3n de 6.000 millones de d\u00f3lares del gasto p\u00fablico en 18 meses, equivalente al 2% del PIB.<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_36465\" class=\"pvc_stats all  \" data-element-id=\"36465\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo gobierno de\u00a0Chile\u00a0anunci\u00f3 el lunes (23.03.2026) un aumento hist\u00f3rico de casi medio d\u00f3lar por litro en los combustibles, tras hacer un severo ajuste en un mecanismo estatal que amortigua la volatilidad de los precios internacionales. Chile depende casi en su totalidad de las importaciones de petr\u00f3leo, cuyo valor en las \u00faltimas semanas registr\u00f3 un [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_36465\" class=\"pvc_stats all  \" data-element-id=\"36465\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":7,"featured_media":36466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17],"tags":[],"class_list":["post-36465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"a3_pvc":{"activated":true,"total_views":19,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=36465"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36465\/revisions"}],"predecessor-version":[{"id":36467,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36465\/revisions\/36467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media\/36466"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=36465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=36465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=36465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}