{"id":36461,"date":"2026-03-24T06:37:09","date_gmt":"2026-03-24T11:07:09","guid":{"rendered":"https:\/\/esviafm.com\/?p=36461"},"modified":"2026-03-24T06:37:09","modified_gmt":"2026-03-24T11:07:09","slug":"trump-dice-que-eeuu-e-iran-han-mantenido-conversaciones-muy-positivas-y-que-no-atacara-las-centrales-electricas-en-cinco-dias","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/trump-dice-que-eeuu-e-iran-han-mantenido-conversaciones-muy-positivas-y-que-no-atacara-las-centrales-electricas-en-cinco-dias\/","title":{"rendered":"Trump dice que EEUU e Ir\u00e1n \u00abhan mantenido conversaciones muy positivas\u00bb y que no atacar\u00e1 las centrales el\u00e9ctricas en cinco d\u00edas"},"content":{"rendered":"<p>El presidente de\u00a0<a title=\"https:\/\/cadenaser.com\/nacional\/2026\/03\/22\/que-pasaria-si-estados-unidos-abandona-la-otan-de-la-desaparicion-de-la-alianza-a-un-nuevo-orden-en-la-organizacion-cadena-ser\/\" href=\"https:\/\/cadenaser.com\/nacional\/2026\/03\/22\/que-pasaria-si-estados-unidos-abandona-la-otan-de-la-desaparicion-de-la-alianza-a-un-nuevo-orden-en-la-organizacion-cadena-ser\/\" target=\"_blank\" rel=\"noopener noreferrer\">Estados Unidos<\/a>,\u00a0<a title=\"https:\/\/cadenaser.com\/nacional\/2026\/03\/23\/trump-instala-en-la-casa-blanca-una-replica-de-la-estatua-de-cristobal-colon-derribada-en-baltimore-en-las-protestas-de-2020-cadena-ser\/\" href=\"https:\/\/cadenaser.com\/nacional\/2026\/03\/23\/trump-instala-en-la-casa-blanca-una-replica-de-la-estatua-de-cristobal-colon-derribada-en-baltimore-en-las-protestas-de-2020-cadena-ser\/\" target=\"_blank\" rel=\"noopener noreferrer\">Donald Trump<\/a>, ha compartido un mensaje en la red social Truth en el que anuncia que \u00abEstados Unidos y Ir\u00e1n han mantenido, durante los \u00faltimos dos d\u00edas, conversaciones muy positivas y productivas sobre la resoluci\u00f3n total de nuestras hostilidades en Oriente Medio\u00bb.<\/p>\n<p>Trump se\u00f1ala adem\u00e1s que, \u00aben vista del tono de estas conversaciones profundas, detalladas y constructivas, que continuar\u00e1n a lo largo de la semana\u00bb, ha instruido al Departamento de Guerra \u00abpara que posponga todos los ataques militares contra centrales el\u00e9ctricas e infraestructura energ\u00e9tica iran\u00edes durante un per\u00edodo de cinco d\u00edas\u00bb. Eso s\u00ed, advierte que est\u00e1 \u00absujeto al \u00e9xito de las reuniones y conversaciones en curso\u00bb.<\/p>\n<p>Tan solo 24 horas antes, este domingo, Trump hab\u00eda reforzado su presi\u00f3n sobre Ir\u00e1n y\u00a0<a title=\"https:\/\/cadenaser.com\/nacional\/2026\/03\/22\/trump-refuerza-su-presion-sobre-iran-y-amenaza-con-atacar-sus-centrales-electricas-si-no-abre-el-estrecho-de-ormuz-en-las-proximas-48-horas-cadena-ser\/\" href=\"https:\/\/cadenaser.com\/nacional\/2026\/03\/22\/trump-refuerza-su-presion-sobre-iran-y-amenaza-con-atacar-sus-centrales-electricas-si-no-abre-el-estrecho-de-ormuz-en-las-proximas-48-horas-cadena-ser\/\" target=\"_blank\" rel=\"noopener noreferrer\">amenazaba con atacar sus centrales el\u00e9ctricas si no abr\u00eda el estrecho de Ormuz en 48 horas<\/a>. Ahora ese ultim\u00e1tum se ampl\u00eda a cinco d\u00edas.<\/p>\n<div class=\"c-sum \">\n<div class=\"oembed twitter\">\n<blockquote class=\"twitter-tweet\"><p>Las palabras del presidente de Estados Unidos han tenido un efecto inmediato en los mercados. La cotizaci\u00f3n del barril de Brent se desploma un 9,7% y cae hasta los 101,5 d\u00f3lares\/barril (ha llegado a caer por debajo de los 100), despu\u00e9s de haber rozado los 114 d\u00f3lares este mismo lunes.<\/p>\n<p>El mensaje de Trump tambi\u00e9n ha dado la vuelta a las bolsas europeas: el Ibex35 ha pasado de caer un 2,5% a rebotar un 1,3% y los principales \u00edndices (DAX, +2,2%; CAC, +1,5%) han pasado al verde despu\u00e9s de amanecer con ca\u00eddas superiores al 1%.<\/p>\n<h2>Ir\u00e1n lo desmiente<\/h2>\n<p>El Ministerio de Exteriores de Ir\u00e1n ha desmentido poco despu\u00e9s que tenga contactos \u00abdirectos e indirectos\u00bb con Estados Unidos. La posici\u00f3n oficial de Teher\u00e1n es que si Trump al final realiza esos ataques, responder\u00e1n minando todo el Golfo P\u00e9rsico.<\/p>\n<p>La agencia de noticias iran\u00ed Tasnim se\u00f1ala que Donald Trump \u00abse ech\u00f3 atr\u00e1s\u00bb a la hora de atacar infraestructuras cr\u00edticas en Ir\u00e1n ante la presi\u00f3n del mercado financiero.<\/p>\n<p>Por su parte, el presidente del Parlamento iran\u00ed, Mohammad Baqer Qalibaf, ha asegurado en redes sociales que no se ha llevado a cabo ning\u00fan tipo de negociaci\u00f3n con Estados Unidos. \u00abNo se han celebrado negociaciones con Estados Unidos, y se utilizan noticias falsas para manipular los mercados financieros y petroleros y escapar del atolladero en el que est\u00e1n atrapados Estados Unidos e Israel\u00bb, ha aseverado en X.<\/p>\n<p>Asimismo, ha se\u00f1alado que el pueblo iran\u00ed \u00abexige un castigo completo y ejemplar para los agresores\u00bb. \u00abTodos los funcionarios iran\u00edes respaldan firmemente a su l\u00edder supremo y a su pueblo hasta que se logre este objetivo\u00bb, ha a\u00f1adido.<\/p>\n<h2>Rusia intermedia por primera vez en la guerra de Ir\u00e1n<\/h2>\n<p>Rusia ha confirmado que ha contactado con EEUU para pedirle que no tengan las instalaciones nucleares de Ir\u00e1n como objetivo militar porque \u00abpueden causar da\u00f1os irreparables\u00bb.<\/p>\n<p>El Kremlin est\u00e1 especialmente preocupado por los ataques contra la central de Bushehr porque all\u00ed trabajan centenares de especialistas rusos.<\/p><\/blockquote>\n<\/div>\n<\/div>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_36461\" class=\"pvc_stats all  \" data-element-id=\"36461\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de\u00a0Estados Unidos,\u00a0Donald Trump, ha compartido un mensaje en la red social Truth en el que anuncia que \u00abEstados Unidos y Ir\u00e1n han mantenido, durante los \u00faltimos dos d\u00edas, conversaciones muy positivas y productivas sobre la resoluci\u00f3n total de nuestras hostilidades en Oriente Medio\u00bb. Trump se\u00f1ala adem\u00e1s que, \u00aben vista del tono de estas [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_36461\" class=\"pvc_stats all  \" data-element-id=\"36461\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":7,"featured_media":36463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17],"tags":[],"class_list":["post-36461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"a3_pvc":{"activated":true,"total_views":18,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=36461"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36461\/revisions"}],"predecessor-version":[{"id":36464,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36461\/revisions\/36464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media\/36463"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=36461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=36461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=36461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}