{"id":36170,"date":"2026-03-16T06:52:34","date_gmt":"2026-03-16T11:22:34","guid":{"rendered":"https:\/\/esviafm.com\/?p=36170"},"modified":"2026-03-16T06:52:34","modified_gmt":"2026-03-16T11:22:34","slug":"presidenta-encargada-insto-a-la-ministra-godoy-a-fortalecer-exportaciones-de-cacao-y-chocolate-venezolano-hacia-mercados-estrategicos","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/presidenta-encargada-insto-a-la-ministra-godoy-a-fortalecer-exportaciones-de-cacao-y-chocolate-venezolano-hacia-mercados-estrategicos\/","title":{"rendered":"Presidenta encargada inst\u00f3 a la ministra Godoy a fortalecer exportaciones de cacao y chocolate venezolano hacia mercados estrat\u00e9gicos"},"content":{"rendered":"<p>La presidenta encargada de la Rep\u00fablica, Delcy Rodr\u00edguez, instruy\u00f3 este domingo a la ministra de Comercio Exterior, Coromoto Godoy, a identificar y consolidar mercados internacionales para potenciar la exportaci\u00f3n del cacao y el chocolate de origen nacional. Durante una visita a la planta de la chocolater\u00eda emprendedora Cakawa, la mandataria (E) enfatiz\u00f3 la necesidad de una activaci\u00f3n inmediata para posicionar este rubro en el comercio mundial.<\/p>\n<div>\u201cUn mensaje a la ministra de comercio exterior, activarse, a ubicar mercado para el chocolate venezolano, para el cacao, instrucci\u00f3n inmediata\u201d, expres\u00f3 Rodr\u00edguez, quien adem\u00e1s solicit\u00f3 al ministro Le\u00f3n Heredia organizar proyectos junto a los emprendedores para facilitar la internacionalizaci\u00f3n del producto.<\/div>\n<div><\/div>\n<div><iframe id=\"instagram-embed-0\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/reel\/DV7H94mDgY-\/embed\/captioned\/?cr=1&amp;v=14&amp;wp=540&amp;rd=https%3A%2F%2Fwww.eluniversal.com&amp;rp=%2Fvenezuela%2F229039%2Fpresidenta-encargada-insto-a-la-ministra-godoy-a-fortalecer-exportaciones-de-cacao-y-chocolate#%7B%22ci%22%3A0%2C%22os%22%3A3731.899999999907%2C%22ls%22%3A485.89999999990687%2C%22le%22%3A3655.7000000001863%7D\" height=\"701\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\" data-instgrm-payload-id=\"instagram-media-payload-0\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div><\/div>\n<div><b>Equiparaci\u00f3n con el sector cafetalero<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div>La jefa de Estado encargada destac\u00f3 que, si bien el sector del caf\u00e9 ha recibido una relevancia significativa en la agenda econ\u00f3mica, el cacao debe ser impulsado bajo la misma estrategia. En este sentido, inform\u00f3 sobre la robusta organizaci\u00f3n del sector:<\/div>\n<div><\/div>\n<div>\n<ul>\n<li>Se ha identificado la siembra de cacao en 17 estados del pa\u00eds.<\/li>\n<li>Existen 1.091 comunidades organizadas con sus propios voceros y voceras del cacao.<\/li>\n<\/ul>\n<\/div>\n<div><\/div>\n<div>El objetivo es elevar la importancia del rubro a niveles de exportaci\u00f3n masiva, aprovechando que el cacao venezolano es considerado \u00abel mejor del mundo\u00bb.<\/div>\n<div><\/div>\n<div><b>Propiedades nutricionales y calidad superior<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div>Durante el recorrido por la planta procesadora, los emprendedores mostraron a la comitiva presidencial el proceso de producci\u00f3n y resaltaron las propiedades cient\u00edficas del fruto nacional. Explicaron que, seg\u00fan estudios realizados con neurocient\u00edficos, el consumo de 30 a 40 gramos diarios de chocolate al 70%, o dos tazas de chocolate oscuro durante 30 d\u00edas, contribuye a la regeneraci\u00f3n de c\u00e9lulas madre y activa endorfinas.<\/div>\n<div><\/div>\n<div>Los productores subrayaron que el cacao venezolano posee entre un 48% y 50% de manteca, componente donde reside la mayor concentraci\u00f3n de vitaminas, prote\u00ednas y beneficios para la salud en comparaci\u00f3n con el cacao de otras naciones.<\/div>\n<div><\/div>\n<div>Finalmente, las representantes de Cakawa explicaron que su modelo de negocio se basa en el impulso de la producci\u00f3n local y el reconocimiento al trabajador del campo. \u201cNosotros aqu\u00ed no vendemos chocolate, vendemos una historia nacional. Cada tableta tiene la historia de su productor, de su finca y de su proceso\u201d, se\u00f1alaron a la mandataria.<\/div>\n<div><\/div>\n<div>Con esta jornada, el Gobierno nacional busca transformar la tradici\u00f3n cacaotera en un pilar de la econom\u00eda diversificada, combinando la organizaci\u00f3n del Poder Popular con la excelencia t\u00e9cnica del procesamiento industrial nacional.<\/div>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_36170\" class=\"pvc_stats all  \" data-element-id=\"36170\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta encargada de la Rep\u00fablica, Delcy Rodr\u00edguez, instruy\u00f3 este domingo a la ministra de Comercio Exterior, Coromoto Godoy, a identificar y consolidar mercados internacionales para potenciar la exportaci\u00f3n del cacao y el chocolate de origen nacional. Durante una visita a la planta de la chocolater\u00eda emprendedora Cakawa, la mandataria (E) enfatiz\u00f3 la necesidad de [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_36170\" class=\"pvc_stats all  \" data-element-id=\"36170\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":7,"featured_media":36171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[25],"tags":[],"class_list":["post-36170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"a3_pvc":{"activated":true,"total_views":21,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=36170"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36170\/revisions"}],"predecessor-version":[{"id":36172,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/36170\/revisions\/36172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media\/36171"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=36170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=36170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=36170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}