{"id":21318,"date":"2024-10-03T08:05:07","date_gmt":"2024-10-03T12:35:07","guid":{"rendered":"https:\/\/esviafm.com\/?p=21318"},"modified":"2024-10-03T08:05:07","modified_gmt":"2024-10-03T12:35:07","slug":"venezuela-se-convierte-en-el-tercer-mayor-proveedor-de-crudo-de-eeuu","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/venezuela-se-convierte-en-el-tercer-mayor-proveedor-de-crudo-de-eeuu\/","title":{"rendered":"Venezuela se convierte en el tercer mayor proveedor de crudo de EEUU"},"content":{"rendered":"<p>Seg\u00fan datos de la Administraci\u00f3n de Informaci\u00f3n Energ\u00e9tica de Estados Unidos (EIA), Venezuela super\u00f3 los 300 mil barriles diarios en exportaciones a EEUU durante el mes de julio, consolid\u00e1ndose como el tercer mayor proveedor de crudo de dicho pa\u00eds.<\/p>\n<div><\/div>\n<div>La recuperaci\u00f3n econ\u00f3mica de Venezuela contin\u00faa tomando fuerza. El pa\u00eds se ha posicionado como el tercer mayor proveedor de crudo a Estados Unidos durante el mes de julio, seg\u00fan datos de la EIA.<\/div>\n<div><\/div>\n<div>EEUU es el mayor productor de petr\u00f3leo del mundo, pero tambi\u00e9n es un gran consumidor del mismo. Para el mes de julio, seg\u00fan la data de la EIA, la naci\u00f3n lleg\u00f3 a importar un total de 7.123.000 barriles por d\u00eda (bpd) de petr\u00f3leo crudo en julio, subiendo el consumo un 6.8 % respecto a junio.<\/p>\n<p>De estas cifras, Venezuela aparece representando el 4.3 %, exportando unos 308.000 bpd, cifra que, en t\u00e9rminos interanuales, duplica lo que exportaba el a\u00f1o pasado en este mismo mes (153.000).<\/p>\n<p>Aunque las relaciones entre Venezuela y Estados Unidos no pasan por su mejor momento, este nivel de exportaciones no se hab\u00eda visto en a\u00f1os, de hecho, se trata de la cifra m\u00e1s alta desde enero de 2019, cuando el pa\u00eds export\u00f3 a EEUU un total de 561.000 bpd.<\/p><\/div>\n<div><\/div>\n<div>Poco despu\u00e9s de ese mes, las exportaciones cayeron a cero, ya que para entonces arribaron las sanciones petroleras del expresidente estadounidense Trump, que imposibilitaron durante tres a\u00f1os importar cualquier cantidad de crudo procedente de Venezuela.<\/p>\n<p>Sin embargo, a inicios de 2023, el Gobierno estadounidense de Biden levant\u00f3 las sanciones impuestas a la industria petrolera en Venezuela durante seis meses, lo que provoc\u00f3 que las empresas extranjeras regresaran lentamente a la Faja Petrol\u00edfera del Orinoco.<\/p>\n<p>En la actualidad, el r\u00e9gimen de sanciones fue restablecido en abril como medida de presi\u00f3n al Gobierno de Maduro, pero ahora las empresas extranjeras tienen la posibilidad de obtener licencias individuales para operar en la industria petrolera del pa\u00eds, lo que permite, sin duda, que su producci\u00f3n y exportaciones sigan en aumento.<\/p><\/div>\n<div><\/div>\n<div>\n<div><b>Venezuela destrona a Arabia Saud\u00ed<\/b><br \/>\nTampoco se puede pasar por alto que Venezuela super\u00f3 en dicho ranking a nada menos que al reino de Arabia Saud\u00ed, el mayor exportador de crudo del mundo y el segundo pa\u00eds con las mayores reservas probadas de petr\u00f3leo (267,000 millones de barriles), superado solo por Venezuela (300,878 millones de barriles, seg\u00fan PDVSA).<\/div>\n<div><\/div>\n<div>Pese a esta gran ventaja num\u00e9rica en reservas, Venezuela a\u00fan no ha sabido sacarle mucho jugo, ya que el pa\u00eds ha estado produciendo m\u00e1s de 900.000 bpd, frente a una media de 3 millones de bpd en sus a\u00f1os dorados.<\/p>\n<p>No obstante, las exportaciones de Venezuela a EEUU en julio fueron suficientes para superar a todos sus rivales m\u00e1s cercanos: Brasil (254.000), Colombia (209.000), Ecuador (169.000) y Guyana (258.000), y se da el lujo de superar a una naci\u00f3n como Arabia Saud\u00ed (280.000). Vale aclarar que esta clasificaci\u00f3n s\u00f3lo se limita a las exportaciones de crudo y no a todos los productos derivados del mismo.<\/p><\/div>\n<\/div>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_21318\" class=\"pvc_stats all  \" data-element-id=\"21318\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan datos de la Administraci\u00f3n de Informaci\u00f3n Energ\u00e9tica de Estados Unidos (EIA), Venezuela super\u00f3 los 300 mil barriles diarios en exportaciones a EEUU durante el mes de julio, consolid\u00e1ndose como el tercer mayor proveedor de crudo de dicho pa\u00eds. La recuperaci\u00f3n econ\u00f3mica de Venezuela contin\u00faa tomando fuerza. El pa\u00eds se ha posicionado como el tercer [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_21318\" class=\"pvc_stats all  \" data-element-id=\"21318\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-21318","post","type-post","status-publish","format-standard","hentry","category-deportes"],"a3_pvc":{"activated":true,"total_views":14,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/21318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=21318"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/21318\/revisions"}],"predecessor-version":[{"id":21320,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/21318\/revisions\/21320"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=21318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=21318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=21318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}