{"id":16603,"date":"2024-07-02T10:36:39","date_gmt":"2024-07-02T15:06:39","guid":{"rendered":"https:\/\/esviafm.com\/?p=16603"},"modified":"2024-07-02T10:36:39","modified_gmt":"2024-07-02T15:06:39","slug":"venezuela-y-china-firman-una-declaracion-conjunta-para-la-cooperacion-espacial","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/venezuela-y-china-firman-una-declaracion-conjunta-para-la-cooperacion-espacial\/","title":{"rendered":"Venezuela y China firman una declaraci\u00f3n conjunta para la cooperaci\u00f3n espacial"},"content":{"rendered":"<p>Caracas, 17 jul (EFE).- La Agencia Bolivariana para Actividades Espaciales (ABAE) de Venezuela y la Administraci\u00f3n Espacial Nacional de China (CNSA) firmaron una declaraci\u00f3n conjunta para la cooperaci\u00f3n en materia de investigaci\u00f3n espacial y la participaci\u00f3n de la naci\u00f3n caribe\u00f1a en el proyecto de la Estaci\u00f3n Internacional de Investigaci\u00f3n Lunar (EIIL), inform\u00f3 este lunes el Ejecutivo del pa\u00eds suramericano.<\/p>\n<p>De esta manera, Venezuela se convierte en el \u201cprimer pa\u00eds del continente americano en unirse a este importante proyecto\u201d, asegur\u00f3 la ministra de Ciencia y Tecnolog\u00eda, Gabriela Jim\u00e9nez, a trav\u00e9s de Twitter.<\/p>\n<p>\u201cLa asociaci\u00f3n estrat\u00e9gica entre Venezuela y China trasciende a todas las \u00e1reas de cooperaci\u00f3n y hoy se constituye en un reconocimiento a los esfuerzos que ha realizado el Gobierno bolivariano en favor del desarrollo cient\u00edfico de nuestro pa\u00eds\u201d, expres\u00f3 la funcionaria.<\/p>\n<p>Durante el encuentro, Jim\u00e9nez se\u00f1al\u00f3 que \u201ctodos los esfuerzos de cooperaci\u00f3n en esta nueva etapa deben dirigirse a la formaci\u00f3n de talentos para la compresi\u00f3n del espacio profundo\u201d, seg\u00fan una nota de prensa de la cartera de Ciencia y Tecnolog\u00eda que ampl\u00eda la informaci\u00f3n.<\/p>\n<p>La delegaci\u00f3n china, de la que forma parte el secretario general de CNSA, Xu Hongliang, destac\u00f3 que es \u201cfundamental\u201d la cooperaci\u00f3n para \u201cincentivar la investigaci\u00f3n cient\u00edfica bilateral, el dise\u00f1o y desarrollo de sondas lunares, el viaje compartido de cargas \u00fatiles cient\u00edficas, los experimentos cient\u00edficos y t\u00e9cnicos, el intercambio y an\u00e1lisis de datos, la educaci\u00f3n y la formaci\u00f3n\u201d.<\/p>\n<p>Con el acuerdo, Venezuela \u201cpone a disposici\u00f3n su infraestructura de estaciones terrenas de control satelital para acompa\u00f1ar, seguir y controlar las misiones espaciales para el env\u00edo de sondas a la Luna\u201d, agreg\u00f3 el ministerio.<\/p>\n<p>China anunci\u00f3 el a\u00f1o pasado la aprobaci\u00f3n de la cuarta fase de su programa de exploraci\u00f3n lunar, que incluye la construcci\u00f3n de esta base de exploraci\u00f3n cient\u00edfica en el polo sur del sat\u00e9lite junto con Rusia.<\/p>\n<p>Pek\u00edn espera completar la construcci\u00f3n de la estructura b\u00e1sica de la EIIL alrededor de 2028, mediante sus futuras sondas lunares Chang\u2019e-6, -7 y -8, seg\u00fan cient\u00edficos del programa espacial chino.<\/p>\n<p>Est\u00e1 previsto que la estaci\u00f3n, en cuyo desarrollo trabajan las agencias espaciales de China y Rusia, est\u00e9 operativa en 2035. EFE<\/p>\n<p><strong>FUENTE: SWISSINFO<\/strong><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_16603\" class=\"pvc_stats all  \" data-element-id=\"16603\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Caracas, 17 jul (EFE).- La Agencia Bolivariana para Actividades Espaciales (ABAE) de Venezuela y la Administraci\u00f3n Espacial Nacional de China (CNSA) firmaron una declaraci\u00f3n conjunta para la cooperaci\u00f3n en materia de investigaci\u00f3n espacial y la participaci\u00f3n de la naci\u00f3n caribe\u00f1a en el proyecto de la Estaci\u00f3n Internacional de Investigaci\u00f3n Lunar (EIIL), inform\u00f3 este lunes el [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_16603\" class=\"pvc_stats all  \" data-element-id=\"16603\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[25],"tags":[],"class_list":["post-16603","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"a3_pvc":{"activated":true,"total_views":32,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/16603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=16603"}],"version-history":[{"count":2,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/16603\/revisions"}],"predecessor-version":[{"id":16606,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/16603\/revisions\/16606"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=16603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=16603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=16603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}