{"id":12851,"date":"2024-04-22T06:30:30","date_gmt":"2024-04-22T11:00:30","guid":{"rendered":"https:\/\/esviafm.com\/?p=12851"},"modified":"2024-04-22T06:30:30","modified_gmt":"2024-04-22T11:00:30","slug":"ministro-marco-torres-inspecciono-construccion-de-canal-de-descarga-en-zuata-y-dique-la-curia-en-aragua","status":"publish","type":"post","link":"https:\/\/esviafm.com\/index.php\/ministro-marco-torres-inspecciono-construccion-de-canal-de-descarga-en-zuata-y-dique-la-curia-en-aragua\/","title":{"rendered":"Ministro Marco Torres inspeccion\u00f3 construcci\u00f3n de canal de descarga en Zuata y dique La Cur\u00eda en Aragua"},"content":{"rendered":"<p>En cumplimiento de las instrucciones del presidente de la Rep\u00fablica, Nicol\u00e1s Maduro, el ministro del Poder Popular de Atenci\u00f3n de las Aguas, G\/D Rodolfo Marco Torres, junto con la gobernadora del estado Aragua, Karina Carpio, la madrina de la entidad, Yelitze Santaella y el presidente de la Hidrocentro, Leonel Ru\u00edz, inspeccionaron los trabajos de construcci\u00f3n del canal de descarga desde el embalse Zuata hac\u00eda el r\u00edo Aragua y rehabilitaci\u00f3n integral del dique La Cur\u00eda.<\/p>\n<p>El ministro inform\u00f3 que esta importante obra hidr\u00e1ulica que se ejecuta en articulaci\u00f3n con el Ministerio del Poder Popular para el Transporte y la Empresa Noroccidental de Mantenimiento y Obras Hidr\u00e1ulicas CA (Enmohca), contempla la edificaci\u00f3n de un aliviadero de concreto armado para controlar la descarga de agua del embalse. \u00abSe han colocado ya 200 metros c\u00fabicos de concreto en el aliviadero, en un trabajo en conjunto entre el gobierno nacional y regional\u00bb, dijo.<\/p>\n<p><span>Las autoridades evaluaron adem\u00e1s los avances de la rehabilitaci\u00f3n integral del dique, construcci\u00f3n de un cimacio para la regulaci\u00f3n de la descarga y sistema de compuertas, esto permitir\u00e1 controlar el agua hacia el Lago Los Tacariguas como parte de las ante el periodo de lluvias.<\/span><\/p>\n<div><\/div>\n<div><span>La gobernadora, Karina Carpio, inform\u00f3 que \u00abes una obra de alta ingenier\u00eda y de alto nivel, que beneficiar\u00e1 a distintos municipios de la entidad, es una obra de prevenci\u00f3n que se ha realizado en tiempo r\u00e9cord con una cuadrilla de trabajadores altamente calificados\u00bb.<\/span><\/p>\n<p><span>Carmen Cannata, encargada de la UTAA Aragua, inform\u00f3 que actualmente hay ocho frentes de trabajo en La Curia, Zuata, Taiguaiguai, 13 de Enero, Aguacatal, La Punta y los canales aductores.<\/span><\/p>\n<p><span>\u00abEl aliviadero es una obra hidr\u00e1ulica de descarga de las aguas pluviales, el canal lograr\u00e1 que el agua proveniente de la lluvia, descargue al r\u00edo Aragua sin ocasionar riesgo de inundaciones aguas abajo\u00bb, expres\u00f3.<\/span><\/p>\n<p><span>Este proyecto forma parte de las 50 l\u00edneas de acci\u00f3n establecidas en el Plan de Rehabilitaci\u00f3n Integral y Control del Lago de Valencia-Los Tacarigua, instruido por el presidente Nicol\u00e1s Maduro, dando respuesta a las solicitudes de las comunidades a trav\u00e9s de la VenApp del 1\u00d7 10 del Buen Gobierno para mejorar el sistema h\u00eddrico.<\/span><\/div>\n<div><\/div>\n<div>FUENTE: EL UNIVERSAL<\/div>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_12851\" class=\"pvc_stats all  \" data-element-id=\"12851\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En cumplimiento de las instrucciones del presidente de la Rep\u00fablica, Nicol\u00e1s Maduro, el ministro del Poder Popular de Atenci\u00f3n de las Aguas, G\/D Rodolfo Marco Torres, junto con la gobernadora del estado Aragua, Karina Carpio, la madrina de la entidad, Yelitze Santaella y el presidente de la Hidrocentro, Leonel Ru\u00edz, inspeccionaron los trabajos de construcci\u00f3n [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_12851\" class=\"pvc_stats all  \" data-element-id=\"12851\" style=\"\"><i class=\"pvc-stats-icon large\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/esviafm.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[25],"tags":[],"class_list":["post-12851","post","type-post","status-publish","format-standard","hentry","category-nacionales"],"a3_pvc":{"activated":true,"total_views":36,"today_views":0},"_links":{"self":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/12851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/comments?post=12851"}],"version-history":[{"count":1,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/12851\/revisions"}],"predecessor-version":[{"id":12853,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/posts\/12851\/revisions\/12853"}],"wp:attachment":[{"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/media?parent=12851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/categories?post=12851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esviafm.com\/index.php\/wp-json\/wp\/v2\/tags?post=12851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}